{"id":81073,"date":"2026-07-14T00:30:22","date_gmt":"2026-07-14T03:30:22","guid":{"rendered":"https:\/\/appservicos.com\/noticias\/projeto-flautistas-da-marambaia-recebe-reconhecimento-da-unesco\/"},"modified":"2026-07-14T00:30:24","modified_gmt":"2026-07-14T03:30:24","slug":"projeto-flautistas-da-marambaia-recebe-reconhecimento-da-unesco","status":"publish","type":"post","link":"https:\/\/appservicos.com\/noticias\/projeto-flautistas-da-marambaia-recebe-reconhecimento-da-unesco\/","title":{"rendered":"Projeto Flautistas da Marambaia recebe reconhecimento da Unesco"},"content":{"rendered":"<div>\n<p>Uma iniciativa que une arte e preserva\u00e7\u00e3o ambiental tem conquistado centenas de estudantes de escolas p\u00fablicas da Zona Oeste do Rio de Janeiro e recebeu, neste ano, reconhecimento da Unesco. <strong>O projeto Flautistas da\u00a0Marambaia realiza, desde 2002, aulas de m\u00fasica e meio ambiente no bairro de Barra de Guaratiba e em comunidades vizinhas.<\/strong><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1696595&#038;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1696595&#038;o=node\"><\/p>\n<p>A a\u00e7\u00e3o \u00e9 organizada pelo Instituto Timbre e conta com parceria do Laborat\u00f3rio de Geografia Marinha e Gest\u00e3o Costeira Integrada da UFRJ, Universidade Federal do Rio de Janeiro. Atualmente as aulas ocorrem no s\u00edtio Burle Marx, Patrim\u00f4nio Mundial reconhecido pela Unesco \u2013 Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Educa\u00e7\u00e3o, a Ci\u00eancia e a Cultura \u2013 e incluem atividades de canto, m\u00fasica e dan\u00e7a, al\u00e9m de a\u00e7\u00f5es de conscientiza\u00e7\u00e3o ambiental.<\/p>\n<p>A proposta \u00e9 aproximar crian\u00e7as e jovens dos ecossistemas da regi\u00e3o, especialmente dos manguezais, al\u00e9m de estimular reflex\u00f5es sobre a import\u00e2ncia da biodiversidade e da cultura.<\/p>\n<p>A presidente do Instituto Timbre, <strong>Luiza Sales<\/strong>, refor\u00e7a a contribui\u00e7\u00e3o do projeto para os participantes:<\/p>\n<blockquote>\n<p>&#8220;Atrav\u00e9s desse projeto, eles t\u00eam a oportunidade de ter contato com diversas linguagens art\u00edsticas e tamb\u00e9m com educa\u00e7\u00e3o ambiental, fazendo com que eles se apropriem cada vez mais do territ\u00f3rio onde vivem e consigam se relacionar com o mundo, com o meio ambiente, atrav\u00e9s da vis\u00e3o que a arte proporciona.&#8221;<\/p>\n<\/blockquote>\n<h3>Objetivos de Desenvolvimento Sustent\u00e1vel da ONU<\/h3>\n<p>A iniciativa est\u00e1 alinhada aos Objetivos de Desenvolvimento Sustent\u00e1vel da ONU, em \u00e1reas como vida terrestre, com foco na preserva\u00e7\u00e3o dos ecossistemas do mangue e do litoral; \u00e1gua pot\u00e1vel e saneamento, ao incentivar a conscientiza\u00e7\u00e3o sobre os recursos h\u00eddricos; e educa\u00e7\u00e3o, por meio do ensino de m\u00fasica, arte e sustentabilidade ambiental.<\/p>\n<p><strong>Luiza Sales<\/strong> destaca que o trabalho tem ganhado reconhecimento:<\/p>\n<blockquote>\n<p>&#8220;Este ano, n\u00f3s recebemos uma chancela da Unesco como uma das a\u00e7\u00f5es pela D\u00e9cada dos Oceanos. Ent\u00e3o, n\u00f3s somos considerados um projeto que contribui para a conscientiza\u00e7\u00e3o e contribui para o objetivo de preserva\u00e7\u00e3o dos oceanos, um dos Objetivos de Desenvolvimento Sustent\u00e1vel da ONU.&#8221;<\/p>\n<\/blockquote>\n<p><strong>Desde a cria\u00e7\u00e3o, o projeto Flautistas da\u00a0Marambaia j\u00e1 atendeu mais de 1,2 mil crian\u00e7as e jovens da regi\u00e3o.<\/strong> Atualmente, re\u00fane cerca de 50 alunos, que participam de aulas de canto, flauta, express\u00e3o corporal, viv\u00eancia c\u00eanica e educa\u00e7\u00e3o ambiental.<\/p>\n<p><em>*Com informa\u00e7\u00f5es da Ag\u00eancia Brasil<\/em><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma iniciativa que une arte e preserva\u00e7\u00e3o ambiental tem conquistado centenas de estudantes de escolas p\u00fablicas da Zona Oeste do Rio de Janeiro e recebeu, neste ano, reconhecimento da Unesco.&hellip;<\/p>\n","protected":false},"author":1,"featured_media":81074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-81073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famosos-tv"],"_links":{"self":[{"href":"https:\/\/appservicos.com\/noticias\/wp-json\/wp\/v2\/posts\/81073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/appservicos.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/appservicos.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/appservicos.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/appservicos.com\/noticias\/wp-json\/wp\/v2\/comments?post=81073"}],"version-history":[{"count":0,"href":"https:\/\/appservicos.com\/noticias\/wp-json\/wp\/v2\/posts\/81073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/appservicos.com\/noticias\/wp-json\/wp\/v2\/media\/81074"}],"wp:attachment":[{"href":"https:\/\/appservicos.com\/noticias\/wp-json\/wp\/v2\/media?parent=81073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/appservicos.com\/noticias\/wp-json\/wp\/v2\/categories?post=81073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/appservicos.com\/noticias\/wp-json\/wp\/v2\/tags?post=81073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}